{"id":1207,"date":"2026-04-18T13:49:06","date_gmt":"2026-04-18T13:49:06","guid":{"rendered":"https:\/\/teifivalleytrail.wales\/events\/lansio-llwybr-dyffryn-teifi\/"},"modified":"2026-04-20T09:28:05","modified_gmt":"2026-04-20T09:28:05","slug":"lansio-llwybr-dyffryn-teifi","status":"publish","type":"tvt_event","link":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/","title":{"rendered":"Lansio Llwybr Dyffryn Teifi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mae Pwyllgor Cymdeithas Llwybr Dyffryn Teifi yn eich gwahodd i ymuno \u00e2 ni ar gyfer lansiad Llwybr Dyffryn Teifi ddydd Sadwrn 25 Ebrill yn y Porth yn Llandysul.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-orange-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2026\/04\/TVT-launch-invite-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Dysgwch fwy<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mae Pwyllgor Cymdeithas Llwybr Dyffryn Teifi yn eich gwahodd i ymuno \u00e2 ni ar gyfer lansio Llwybr Dyffryn Teifi.  <\/p>\n","protected":false},"featured_media":1204,"template":"","class_list":["post-1207","tvt_event","type-tvt_event","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lansio Llwybr Dyffryn Teifi - Teifi Valley Trail<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/\" \/>\n<meta property=\"og:locale\" content=\"cy_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lansio Llwybr Dyffryn Teifi - Teifi Valley Trail\" \/>\n<meta property=\"og:description\" content=\"Mae Pwyllgor Cymdeithas Llwybr Dyffryn Teifi yn eich gwahodd i ymuno \u00e2 ni ar gyfer lansio Llwybr Dyffryn Teifi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/\" \/>\n<meta property=\"og:site_name\" content=\"Teifi Valley Trail\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T09:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2026\/04\/TVT-Group-1-crop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2026\" \/>\n\t<meta property=\"og:image:height\" content=\"1548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/\",\"url\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/\",\"name\":\"Lansio Llwybr Dyffryn Teifi - Teifi Valley Trail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teifivalleytrail.wales\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/TVT-Group-1-crop.jpg\",\"datePublished\":\"2026-04-18T13:49:06+00:00\",\"dateModified\":\"2026-04-20T09:28:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/#breadcrumb\"},\"inLanguage\":\"cy-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cy-GB\",\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teifivalleytrail.wales\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/TVT-Group-1-crop.jpg\",\"contentUrl\":\"https:\\\/\\\/teifivalleytrail.wales\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/TVT-Group-1-crop.jpg\",\"width\":2026,\"height\":1548,\"caption\":\"Teifi Valley Trail Association committee\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/lansio-llwybr-dyffryn-teifi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digwyddiadau\",\"item\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lansio Llwybr Dyffryn Teifi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/#website\",\"url\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/\",\"name\":\"Teifi Valley Trail\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cy-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/#organization\",\"name\":\"Teifi Valley Trail\",\"url\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cy-GB\",\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teifivalleytrail.wales\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/white-logo.svg\",\"contentUrl\":\"https:\\\/\\\/teifivalleytrail.wales\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/white-logo.svg\",\"width\":230,\"height\":50,\"caption\":\"Teifi Valley Trail\"},\"image\":{\"@id\":\"https:\\\/\\\/teifivalleytrail.wales\\\/cy\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lansio Llwybr Dyffryn Teifi - Teifi Valley Trail","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/","og_locale":"cy_GB","og_type":"article","og_title":"Lansio Llwybr Dyffryn Teifi - Teifi Valley Trail","og_description":"Mae Pwyllgor Cymdeithas Llwybr Dyffryn Teifi yn eich gwahodd i ymuno \u00e2 ni ar gyfer lansio Llwybr Dyffryn Teifi.","og_url":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/","og_site_name":"Teifi Valley Trail","article_modified_time":"2026-04-20T09:28:05+00:00","og_image":[{"width":2026,"height":1548,"url":"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2026\/04\/TVT-Group-1-crop.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/","url":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/","name":"Lansio Llwybr Dyffryn Teifi - Teifi Valley Trail","isPartOf":{"@id":"https:\/\/teifivalleytrail.wales\/cy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/#primaryimage"},"image":{"@id":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/#primaryimage"},"thumbnailUrl":"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2026\/04\/TVT-Group-1-crop.jpg","datePublished":"2026-04-18T13:49:06+00:00","dateModified":"2026-04-20T09:28:05+00:00","breadcrumb":{"@id":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/#breadcrumb"},"inLanguage":"cy-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/"]}]},{"@type":"ImageObject","inLanguage":"cy-GB","@id":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/#primaryimage","url":"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2026\/04\/TVT-Group-1-crop.jpg","contentUrl":"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2026\/04\/TVT-Group-1-crop.jpg","width":2026,"height":1548,"caption":"Teifi Valley Trail Association committee"},{"@type":"BreadcrumbList","@id":"https:\/\/teifivalleytrail.wales\/cy\/events\/lansio-llwybr-dyffryn-teifi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teifivalleytrail.wales\/cy\/"},{"@type":"ListItem","position":2,"name":"Digwyddiadau","item":"https:\/\/teifivalleytrail.wales\/cy\/events\/"},{"@type":"ListItem","position":3,"name":"Lansio Llwybr Dyffryn Teifi"}]},{"@type":"WebSite","@id":"https:\/\/teifivalleytrail.wales\/cy\/#website","url":"https:\/\/teifivalleytrail.wales\/cy\/","name":"Teifi Valley Trail","description":"","publisher":{"@id":"https:\/\/teifivalleytrail.wales\/cy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teifivalleytrail.wales\/cy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cy-GB"},{"@type":"Organization","@id":"https:\/\/teifivalleytrail.wales\/cy\/#organization","name":"Teifi Valley Trail","url":"https:\/\/teifivalleytrail.wales\/cy\/","logo":{"@type":"ImageObject","inLanguage":"cy-GB","@id":"https:\/\/teifivalleytrail.wales\/cy\/#\/schema\/logo\/image\/","url":"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2024\/02\/white-logo.svg","contentUrl":"https:\/\/teifivalleytrail.wales\/wp-content\/uploads\/2024\/02\/white-logo.svg","width":230,"height":50,"caption":"Teifi Valley Trail"},"image":{"@id":"https:\/\/teifivalleytrail.wales\/cy\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/teifivalleytrail.wales\/cy\/wp-json\/wp\/v2\/events\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teifivalleytrail.wales\/cy\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/teifivalleytrail.wales\/cy\/wp-json\/wp\/v2\/types\/tvt_event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teifivalleytrail.wales\/cy\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/teifivalleytrail.wales\/cy\/wp-json\/wp\/v2\/media?parent=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}